{"id":46977,"date":"2021-01-29T12:34:19","date_gmt":"2021-01-29T11:34:19","guid":{"rendered":"https:\/\/millerweldseurope.com\/ueber-uns\/karriere\/"},"modified":"2026-05-28T08:16:14","modified_gmt":"2026-05-28T06:16:14","slug":"karriere","status":"publish","type":"page","link":"https:\/\/millerweldseurope.com\/de\/ueber-uns\/karriere\/","title":{"rendered":"Karriere"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"46977\" class=\"elementor elementor-46977 elementor-1777\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fab62a4 e-ecs-flex e-flex e-con-boxed e-con e-parent\" data-id=\"fab62a4\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;video&quot;,&quot;background_video_link&quot;:&quot;\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/webopener_miller_2-1080p.mp4&quot;,&quot;background_play_on_mobile&quot;:&quot;yes&quot;,&quot;ecs_container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-background-video-container\">\n\t\t\t\t\t\t\t<video class=\"elementor-background-video-hosted\" role=\"presentation\" autoplay muted playsinline loop><\/video>\n\t\t\t\t\t<\/div>\t\t<div class=\"elementor-element elementor-element-5ccb8a6 elementor-widget__width-inherit miller-text-shadow hp-typed-text elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"5ccb8a6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"typed-me\" data-string0=\"Wir sind stark im Team.\" data-string1=\"Wir sind voller Energie.\" data-string2=\"Wir geben alles.\" data-string3=\"Wir sind mit Herz und Leidenschaft dabei.\" data-string4=\"Wir z\u00e4hlen auf jeden Einzelnen.\" data-string5=\"Wir sind dein Sprungbrett in die Zukunft.\" data-string6=\"Wir bauen auf dich.\" data-string7=\"Wir wollen herausragend sein.\" data-type-speed=\"0\" data-start-delay=\"0\" data-back-speed=\"0\" data-back-delay=\"800\"><\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8295f14 e-con-full e-ecs-flex e-flex elementor-invisible e-con e-child\" data-id=\"8295f14\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInRight&quot;,&quot;animation_delay&quot;:200,&quot;ecs_container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f701900 elementor-widget__width-inherit miller-text-shadow elementor-widget elementor-widget-heading\" data-id=\"f701900\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Miller\u00ae for the people who build our world.<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-148b3ed elementor-widget__width-auto elementor-widget elementor-widget-button\" data-id=\"148b3ed\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#current_openings\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Stellenangebote anzeigen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9d41810 e-ecs-flex e-flex e-con-boxed elementor-invisible e-con e-parent\" data-id=\"9d41810\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;ecs_container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-62a1b8e elementor-widget elementor-widget-text-editor\" data-id=\"62a1b8e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Wir haben uns Spitzenleistungen in der Schwei\u00dftechnik verschrieben und erweitern die Grenzen des M\u00f6glichen. Wir gestalten unsichtbar die sichere Welt von morgen. Ob beim Dinner, Bereisen der Welt oder dem t\u00e4glichen Surfen im Netz \u2013 die pr\u00e4zisen, robusten Schwei\u00dfn\u00e4hte der Miller Produkte sind in vielf\u00e4ltigen Lebensbereichen unverzichtbar.<\/p><p>Genauso unverzichtbar wie jeder Einzelne in unserem Team. Mit Begeisterung f\u00fcr smarte, erstklassige Schwei\u00dfl\u00f6sungen, echtem Teamgeist und positivem Spirit sind wir ambitioniert, unseren Exzellenzanspruch heute und in Zukunft zu erf\u00fcllen. Bist du bereit, deine Ambitionen mit unseren zu verbinden?<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7a6b3bd e-ecs-flex e-flex e-con-boxed e-con e-parent\" data-id=\"7a6b3bd\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;ecs_container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-842a108 elementor-widget elementor-widget-heading\" data-id=\"842a108\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Wir schaffen Verbindungen \u2013 zwischen Menschen, Ideen und Technologien.<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c9fea83 e-grid e-con-full e-ecs-grid e-con e-child\" data-id=\"c9fea83\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ecs_container_type&quot;:&quot;grid&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-57cfbd3 e-con-full e-ecs-flex e-flex e-con e-child\" data-id=\"57cfbd3\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;ecs_container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e06aac6 elementor-widget elementor-widget-image\" data-id=\"e06aac6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/millerweldseurope.com\/wp-content\/uploads\/2025\/11\/intro_01-1-768x512.jpg\" class=\"attachment-medium_large size-medium_large wp-image-54739\" alt=\"\" srcset=\"https:\/\/millerweldseurope.com\/wp-content\/uploads\/2025\/11\/intro_01-1-768x512.jpg 768w, https:\/\/millerweldseurope.com\/wp-content\/uploads\/2025\/11\/intro_01-1-300x200.jpg 300w, https:\/\/millerweldseurope.com\/wp-content\/uploads\/2025\/11\/intro_01-1-1024x683.jpg 1024w, https:\/\/millerweldseurope.com\/wp-content\/uploads\/2025\/11\/intro_01-1.jpg 1080w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2a3d364 elementor-widget elementor-widget-heading\" data-id=\"2a3d364\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Wir sind echte Teamplayer\u200b<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b4b25ab elementor-widget elementor-widget-text-editor\" data-id=\"b4b25ab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Wir respektieren und vertrauen uns und interagieren auf Augenh\u00f6he \u2013 bei uns herrscht eine lockere, famili\u00e4re &#8222;Du&#8220;-Kultur, die Barrieren abbaut und Verbindungen schafft. Wir unterst\u00fctzen uns gegenseitig mit einer positiven Einstellung und Extraportion guter Laune, die den Weg f\u00fcr frische Ideen und echte Zusammenarbeit ebnen. Nur gemeinsam bringen wir Miller voran!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-811bdf3 e-con-full e-ecs-flex e-flex e-con e-child\" data-id=\"811bdf3\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;ecs_container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-25dffa9 elementor-widget elementor-widget-image\" data-id=\"25dffa9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/millerweldseurope.com\/wp-content\/uploads\/2025\/11\/intro_02_new-1-768x512.jpg\" class=\"attachment-medium_large size-medium_large wp-image-54744\" alt=\"\" srcset=\"https:\/\/millerweldseurope.com\/wp-content\/uploads\/2025\/11\/intro_02_new-1-768x512.jpg 768w, https:\/\/millerweldseurope.com\/wp-content\/uploads\/2025\/11\/intro_02_new-1-300x200.jpg 300w, https:\/\/millerweldseurope.com\/wp-content\/uploads\/2025\/11\/intro_02_new-1-1024x683.jpg 1024w, https:\/\/millerweldseurope.com\/wp-content\/uploads\/2025\/11\/intro_02_new-1.jpg 1080w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-866cc99 elementor-widget elementor-widget-heading\" data-id=\"866cc99\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Wir tun was wir sagen\u200b<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b423e8f elementor-widget elementor-widget-text-editor\" data-id=\"b423e8f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Wir sind mit vollem Einsatz, Leidenschaft und Herzblut bei der Sache und geben jederzeit unser Bestes. Wir stehen f\u00fcr echte Werte und klare Worte. Was wir sagen, meinen wir auch so und setzen es um. Unsere Werte leiten uns und machen uns zu dem, was wir sind.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0917b5f e-con-full e-ecs-flex e-flex e-con e-child\" data-id=\"0917b5f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;ecs_container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d4c5037 elementor-widget elementor-widget-image\" data-id=\"d4c5037\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/millerweldseurope.com\/wp-content\/uploads\/2025\/11\/intro_03-1-1024x683.jpg\" class=\"attachment-large size-large wp-image-54749\" alt=\"\" srcset=\"https:\/\/millerweldseurope.com\/wp-content\/uploads\/2025\/11\/intro_03-1-1024x683.jpg 1024w, https:\/\/millerweldseurope.com\/wp-content\/uploads\/2025\/11\/intro_03-1-300x200.jpg 300w, https:\/\/millerweldseurope.com\/wp-content\/uploads\/2025\/11\/intro_03-1-768x512.jpg 768w, https:\/\/millerweldseurope.com\/wp-content\/uploads\/2025\/11\/intro_03-1.jpg 1080w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ce7a9d1 elementor-widget elementor-widget-heading\" data-id=\"ce7a9d1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Jeder Einzelne z\u00e4hlt\u200b<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c1d652a elementor-widget elementor-widget-text-editor\" data-id=\"c1d652a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Bei uns bringt sich jeder aktiv ein, ob Produktionsmitarbeiter oder Gesch\u00e4ftsf\u00fchrung! Mit kreativen Ideen in der Entwicklung, geschickten Handgriffen in der Montage oder wachem Zahlenverstand im Finanzwesen: Verantwortung wird bei uns nicht nur gegeben, sondern gelebt. Mit Vertrauen, Raum f\u00fcr eigene Entscheidungen und echter Hands-On-Mentalit\u00e4t gestalten wir gemeinsam den Erfolg von Miller.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-94cd5b3 e-con-full e-ecs-flex e-flex e-con e-child\" data-id=\"94cd5b3\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;ecs_container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-547213d elementor-widget elementor-widget-image\" data-id=\"547213d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/millerweldseurope.com\/wp-content\/uploads\/2025\/11\/intro_04-1-768x512.jpg\" class=\"attachment-medium_large size-medium_large wp-image-54754\" alt=\"\" srcset=\"https:\/\/millerweldseurope.com\/wp-content\/uploads\/2025\/11\/intro_04-1-768x512.jpg 768w, https:\/\/millerweldseurope.com\/wp-content\/uploads\/2025\/11\/intro_04-1-300x200.jpg 300w, https:\/\/millerweldseurope.com\/wp-content\/uploads\/2025\/11\/intro_04-1-1024x683.jpg 1024w, https:\/\/millerweldseurope.com\/wp-content\/uploads\/2025\/11\/intro_04-1.jpg 1080w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9f41a88 elementor-widget elementor-widget-heading\" data-id=\"9f41a88\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Wir verbinden Unternehmenswelten\u200b<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-617cba7 elementor-widget elementor-widget-text-editor\" data-id=\"617cba7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Bei uns findest du eine mittelst\u00e4ndische Kultur und die Power eines Gro\u00dfkonzerns: Kurze Wege, schnelle Entscheidungen, flache Hierarchien sowie Stabilit\u00e4t und Sicherheit. Mit ITW als Global Player im R\u00fccken agieren wir international und am Puls der Zeit. Wir sind innerhalb Europas in Singen Zuhause \u2013 Zuhause f\u00fchlen wir uns jedoch in der ganzen Welt.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6640f6a e-con-full e-ecs-flex e-flex e-con e-child\" data-id=\"6640f6a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;ecs_container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1edec9a elementor-widget elementor-widget-image\" data-id=\"1edec9a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/millerweldseurope.com\/wp-content\/uploads\/2025\/11\/intro_06-1-768x512.jpg\" class=\"attachment-medium_large size-medium_large wp-image-54759\" alt=\"\" srcset=\"https:\/\/millerweldseurope.com\/wp-content\/uploads\/2025\/11\/intro_06-1-768x512.jpg 768w, https:\/\/millerweldseurope.com\/wp-content\/uploads\/2025\/11\/intro_06-1-300x200.jpg 300w, https:\/\/millerweldseurope.com\/wp-content\/uploads\/2025\/11\/intro_06-1-1024x683.jpg 1024w, https:\/\/millerweldseurope.com\/wp-content\/uploads\/2025\/11\/intro_06-1.jpg 1080w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-68d9a18 elementor-widget elementor-widget-heading\" data-id=\"68d9a18\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Wir sind Ideenschmiede<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2491b50 elementor-widget elementor-widget-text-editor\" data-id=\"2491b50\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Bei uns stehen herausragende Schwei\u00dfl\u00f6sungen an erster Stelle \u2013 immer mit Blick auf die Bed\u00fcrfnisse unserer Kunden. Mit Herz und Verstand entwickeln wir Ideen, die den Alltag unserer Kunden vereinfachen. Unser Ziel: Begeistern und Erleichtern, jeden Tag aufs Neue.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-551dbc4 e-ecs-flex e-flex e-con-boxed e-con e-child\" data-id=\"551dbc4\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;ecs_container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0e78740 elementor-widget elementor-widget-image\" data-id=\"0e78740\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/millerweldseurope.com\/wp-content\/uploads\/2025\/11\/intro_05_new-1-768x512.jpg\" class=\"attachment-medium_large size-medium_large wp-image-54764\" alt=\"\" srcset=\"https:\/\/millerweldseurope.com\/wp-content\/uploads\/2025\/11\/intro_05_new-1-768x512.jpg 768w, https:\/\/millerweldseurope.com\/wp-content\/uploads\/2025\/11\/intro_05_new-1-300x200.jpg 300w, https:\/\/millerweldseurope.com\/wp-content\/uploads\/2025\/11\/intro_05_new-1-1024x683.jpg 1024w, https:\/\/millerweldseurope.com\/wp-content\/uploads\/2025\/11\/intro_05_new-1.jpg 1080w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8ff8b8d elementor-widget elementor-widget-heading\" data-id=\"8ff8b8d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Wir sind dynamisch\u200b<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7b01c2e elementor-widget elementor-widget-text-editor\" data-id=\"7b01c2e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Auf solider Grundlage wachsen wir ehrgeizig stetig \u00fcber uns hinaus und sichern schon heute die Spitzenposition von Miller f\u00fcr morgen. Ambitioniert Schritt f\u00fcr Schritt in die Zukunft.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c87f8ec e-ecs-flex e-flex e-con-boxed e-con e-parent\" data-id=\"c87f8ec\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;ecs_container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4957640 elementor-widget elementor-widget-heading\" data-id=\"4957640\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Das erwartet Dich in unserer Arbeitswelt.<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7996123 e-con-full e-ecs-flex e-flex e-con e-child\" data-id=\"7996123\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ecs_container_type&quot;:&quot;flex&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-4a2e8da e-con-full e-ecs-flex e-flex e-con e-child\" data-id=\"4a2e8da\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ecs_container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ee3c2bb elementor-widget elementor-widget-heading\" data-id=\"ee3c2bb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">Dein Arbeitsplatz<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b199054 candidate-profile elementor-widget elementor-widget-text-editor\" data-id=\"b199054\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Moderne, offene B\u00fcros<br \/><\/strong>Und eine helle, angenehme Arbeitsatmosph\u00e4re in der Logistik<\/p><p><strong>Top-Ausstattung<br \/><\/strong>Mit modernster Hardware und Software<\/p><p><strong>Flexible Arbeitszeiten (Gleitzeit) <br \/><\/strong>F\u00fcr eine positive Work Life Balance in allen Bereichen<\/p><p><strong>Arbeiten wo du m\u00f6chtest <br \/><\/strong>Mit unserem Mobile Office Angebot<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-59db2d1 e-con-full e-ecs-flex e-flex e-con e-child\" data-id=\"59db2d1\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ecs_container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4698b0f elementor-widget elementor-widget-image\" data-id=\"4698b0f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/millerweldseurope.com\/wp-content\/uploads\/2025\/11\/intro_07-1-1024x683.jpg\" class=\"attachment-large size-large wp-image-54769\" alt=\"\" srcset=\"https:\/\/millerweldseurope.com\/wp-content\/uploads\/2025\/11\/intro_07-1-1024x683.jpg 1024w, https:\/\/millerweldseurope.com\/wp-content\/uploads\/2025\/11\/intro_07-1-300x200.jpg 300w, https:\/\/millerweldseurope.com\/wp-content\/uploads\/2025\/11\/intro_07-1-768x512.jpg 768w, https:\/\/millerweldseurope.com\/wp-content\/uploads\/2025\/11\/intro_07-1.jpg 1080w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8e5786f e-con-full e-ecs-flex e-flex e-con e-child\" data-id=\"8e5786f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ecs_container_type&quot;:&quot;flex&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-74a19d4 e-con-full e-ecs-flex e-flex e-con e-child\" data-id=\"74a19d4\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ecs_container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-65e3480 elementor-widget elementor-widget-heading\" data-id=\"65e3480\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">Deine Benefits<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4e0384f candidate-profile elementor-widget elementor-widget-text-editor\" data-id=\"4e0384f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>G\u00f6nn\u2018 dir was<\/strong><br \/>Mit exklusiven Rabatten und vielf\u00e4ltigen Angeboten \u00fcber unser Corporate Benefits Portal<\/p><p><strong>Vernetze dich<\/strong><br \/>Bei spannenden Events der ITW Mitarbeitergruppen, z.B. \u201eInternational Women\u2019s Network\u201c oder \u201eYoung Professionals Network\u201c<\/p><p><strong>Bleib\u2018 fit<\/strong><br \/>Mit unserer Fitness-Studio-Kooperation, einem Jobrad oder gemeinsamen Bewegungspausen mit einem Fitnesstrainer in der europ\u00e4ischen Miller-Zentrale in Singen<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e62a922 e-con-full e-ecs-flex e-flex e-con e-child\" data-id=\"e62a922\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ecs_container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1c35287 elementor-widget elementor-widget-image\" data-id=\"1c35287\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/millerweldseurope.com\/wp-content\/uploads\/2025\/11\/intro_08-1-1024x683.jpg\" class=\"attachment-large size-large wp-image-54774\" alt=\"\" srcset=\"https:\/\/millerweldseurope.com\/wp-content\/uploads\/2025\/11\/intro_08-1-1024x683.jpg 1024w, https:\/\/millerweldseurope.com\/wp-content\/uploads\/2025\/11\/intro_08-1-300x200.jpg 300w, https:\/\/millerweldseurope.com\/wp-content\/uploads\/2025\/11\/intro_08-1-768x512.jpg 768w, https:\/\/millerweldseurope.com\/wp-content\/uploads\/2025\/11\/intro_08-1.jpg 1080w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b1c117b e-con-full e-ecs-flex e-flex e-con e-child\" data-id=\"b1c117b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ecs_container_type&quot;:&quot;flex&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-9e318a1 e-con-full e-ecs-flex e-flex e-con e-child\" data-id=\"9e318a1\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ecs_container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d784469 elementor-widget elementor-widget-heading\" data-id=\"d784469\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">Dein Onboarding<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7d52779 candidate-profile elementor-widget elementor-widget-text-editor\" data-id=\"7d52779\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Individuell und strukturiert<\/strong><br \/>Mit einem auf dich zugeschnittenen Onboarding-Plan<\/p><p><strong>Pers\u00f6nlich und mit umfassendem Support<\/strong><br \/>Durch hilfsbereite Kolleginnen und Kollegen und einem pers\u00f6nlichen Buddy<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-59ebeff e-con-full e-ecs-flex e-flex e-con e-child\" data-id=\"59ebeff\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ecs_container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d4e4330 elementor-widget elementor-widget-image\" data-id=\"d4e4330\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/millerweldseurope.com\/wp-content\/uploads\/2025\/11\/intro_09-1-1024x683.jpg\" class=\"attachment-large size-large wp-image-54779\" alt=\"\" srcset=\"https:\/\/millerweldseurope.com\/wp-content\/uploads\/2025\/11\/intro_09-1-1024x683.jpg 1024w, https:\/\/millerweldseurope.com\/wp-content\/uploads\/2025\/11\/intro_09-1-300x200.jpg 300w, https:\/\/millerweldseurope.com\/wp-content\/uploads\/2025\/11\/intro_09-1-768x512.jpg 768w, https:\/\/millerweldseurope.com\/wp-content\/uploads\/2025\/11\/intro_09-1.jpg 1080w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2c8567b e-con-full e-ecs-flex e-flex e-con e-child\" data-id=\"2c8567b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ecs_container_type&quot;:&quot;flex&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-556cc7e e-con-full e-ecs-flex e-flex e-con e-child\" data-id=\"556cc7e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ecs_container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c63117c elementor-widget elementor-widget-heading\" data-id=\"c63117c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">Deine pers\u00f6nliche und berufliche Entwicklung<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8774620 candidate-profile elementor-widget elementor-widget-text-editor\" data-id=\"8774620\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Vorgesetzte, die Dich unterst\u00fctzen<\/strong><br \/>Sie helfen dir deine St\u00e4rken zu entdecken und fordern und f\u00f6rdern dich, damit du \u00fcber dich hinausw\u00e4chst<\/p><p><strong>J\u00e4hrliche Gespr\u00e4che auf Augenh\u00f6he<\/strong><br \/>Um gemeinsam Ziele und Visionen zu besprechen<\/p><p><strong>Weiterbildung, die zu dir passt<\/strong><br \/>Abgestimmt auf dich und deine beruflichen Perspektiven<\/p><p><strong>Entwicklungschancen im gro\u00dfen Stil<\/strong><br \/>Entwickle dich innerhalb von Miller oder in der gro\u00dfen ITW-Familie<\/p><p><strong>F\u00f6rderung von Talenten<\/strong><br \/>Wir bieten High Potentials ma\u00dfgeschneiderte M\u00f6glichkeiten zur Entwicklung<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-dcae2ed e-con-full e-ecs-flex e-flex e-con e-child\" data-id=\"dcae2ed\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ecs_container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4aab0f8 elementor-widget elementor-widget-image\" data-id=\"4aab0f8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/millerweldseurope.com\/wp-content\/uploads\/2025\/11\/intro_10-1-1024x683.jpg\" class=\"attachment-large size-large wp-image-54784\" alt=\"\" srcset=\"https:\/\/millerweldseurope.com\/wp-content\/uploads\/2025\/11\/intro_10-1-1024x683.jpg 1024w, https:\/\/millerweldseurope.com\/wp-content\/uploads\/2025\/11\/intro_10-1-300x200.jpg 300w, https:\/\/millerweldseurope.com\/wp-content\/uploads\/2025\/11\/intro_10-1-768x512.jpg 768w, https:\/\/millerweldseurope.com\/wp-content\/uploads\/2025\/11\/intro_10-1.jpg 1080w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d976e6d e-ecs-flex e-flex e-con-boxed e-con e-parent\" data-id=\"d976e6d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;ecs_container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0efa911 elementor-widget elementor-widget-heading\" data-id=\"0efa911\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Wir sind ein Team, das anpackt und weiterdenkt.<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4989cad testimonials-slider elementor-arrows-position-inside elementor-widget elementor-widget-n-carousel\" data-id=\"4989cad\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;carousel_items&quot;:[{&quot;slide_title&quot;:&quot;Slide 1&quot;,&quot;_id&quot;:&quot;4a94379&quot;},{&quot;slide_title&quot;:&quot;Slide 1&quot;,&quot;_id&quot;:&quot;d424dae&quot;},{&quot;slide_title&quot;:&quot;Slide 1&quot;,&quot;_id&quot;:&quot;ad0e4c2&quot;},{&quot;slide_title&quot;:&quot;Slide 1&quot;,&quot;_id&quot;:&quot;9fab836&quot;},{&quot;slide_title&quot;:&quot;Slide 1&quot;,&quot;_id&quot;:&quot;2b73bf5&quot;},{&quot;slide_title&quot;:&quot;Slide 1&quot;,&quot;_id&quot;:&quot;a208c62&quot;}],&quot;slides_to_show&quot;:&quot;3&quot;,&quot;slides_to_show_tablet&quot;:&quot;2&quot;,&quot;slides_to_show_mobile&quot;:&quot;1&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;offset_sides&quot;:&quot;none&quot;,&quot;arrows&quot;:&quot;yes&quot;,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;image_spacing_custom_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-carousel swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Karussell\" dir=\"ltr\">\n\t\t\t<div class=\"swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"1\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 von 6\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-085d91a e-ecs-flex e-flex e-con-boxed e-con e-child\" data-id=\"085d91a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ecs_container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-aedc1c4 elementor-widget elementor-widget-image\" data-id=\"aedc1c4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/millerweldseurope.com\/wp-content\/uploads\/2025\/11\/testi_jb_amadiang-1-1024x683.jpg\" class=\"attachment-large size-large wp-image-54808\" alt=\"\" srcset=\"https:\/\/millerweldseurope.com\/wp-content\/uploads\/2025\/11\/testi_jb_amadiang-1-1024x683.jpg 1024w, https:\/\/millerweldseurope.com\/wp-content\/uploads\/2025\/11\/testi_jb_amadiang-1-300x200.jpg 300w, https:\/\/millerweldseurope.com\/wp-content\/uploads\/2025\/11\/testi_jb_amadiang-1-768x512.jpg 768w, https:\/\/millerweldseurope.com\/wp-content\/uploads\/2025\/11\/testi_jb_amadiang-1.jpg 1080w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c7e6eb7 elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"c7e6eb7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Jean Baptiste Amadiang<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7da75f0 elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"7da75f0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Area Sales Manager Sub-Saharan Africa<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e5c4610 team-carousel_bio elementor-widget elementor-widget-text-editor\" data-id=\"e5c4610\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>F\u00fcr mich ist die Arbeit bei ITW mehr als nur Teil eines tollen Teams zu sein. Bei ITW wird jeder Mitarbeitende mit Respekt behandelt, das Arbeitsumfeld ist angenehm und die Kolleg: innen sind gro\u00dfartig. Die Kommunikation untereinander funktioniert hervorragend \u2013 man bekommt jederzeit Unterst\u00fctzung, wenn man darum bittet. Und: ITW h\u00e4lt, was es seinen Mitarbeitenden verspricht. Mit Menschen aus aller Welt zu arbeiten ist spannend und inspirierend zugleich.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"2\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 von 6\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8f259b9 e-ecs-flex e-flex e-con-boxed e-con e-child\" data-id=\"8f259b9\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ecs_container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ad19ad4 elementor-widget elementor-widget-image\" data-id=\"ad19ad4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/millerweldseurope.com\/wp-content\/uploads\/2025\/11\/testi_f_karaduman-1024x683.jpg\" class=\"attachment-large size-large wp-image-54698\" alt=\"\" srcset=\"https:\/\/millerweldseurope.com\/wp-content\/uploads\/2025\/11\/testi_f_karaduman-1024x683.jpg 1024w, https:\/\/millerweldseurope.com\/wp-content\/uploads\/2025\/11\/testi_f_karaduman-300x200.jpg 300w, https:\/\/millerweldseurope.com\/wp-content\/uploads\/2025\/11\/testi_f_karaduman-768x512.jpg 768w, https:\/\/millerweldseurope.com\/wp-content\/uploads\/2025\/11\/testi_f_karaduman.jpg 1080w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-69fca01 elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"69fca01\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Filiz Karaduman<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6695132 elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"6695132\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Area Sales Manager - Eastern Europe &amp; Turkey <\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-029af1f team-carousel_bio elementor-widget elementor-widget-text-editor\" data-id=\"029af1f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Seit \u00fcber zehn Jahren arbeite ich mit dem ITW Business Model \u2013 und es hat mir viele neue Perspektiven er\u00f6ffnet. Die dezentrale, unternehmerische Kultur ermutigt mich, wie ein Eigent\u00fcmer zu denken und zu handeln. Dieses Vertrauen hilft mir, die richtigen Entscheidungen zu treffen und Ergebnisse zu erzielen. Das 80\/20-Prinzip hat mein professionelles Arbeiten gepr\u00e4gt: Ich fokussiere mich auf das Wesentliche und manage meine Zeit effizient. Die Marke Miller blickt auf \u00fcber 100 Jahre Geschichte zur\u00fcck \u2013 und ich bin stolz, Teil des Teams zu sein, das diese renommierte Marke in Europa repr\u00e4sentiert.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"3\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 von 6\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2c4c974 e-ecs-flex e-flex e-con-boxed e-con e-child\" data-id=\"2c4c974\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ecs_container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c8b6943 elementor-widget elementor-widget-image\" data-id=\"c8b6943\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/millerweldseurope.com\/wp-content\/uploads\/2025\/11\/fab-1024x683.jpg\" class=\"attachment-large size-large wp-image-54825\" alt=\"\" srcset=\"https:\/\/millerweldseurope.com\/wp-content\/uploads\/2025\/11\/fab-1024x683.jpg 1024w, https:\/\/millerweldseurope.com\/wp-content\/uploads\/2025\/11\/fab-300x200.jpg 300w, https:\/\/millerweldseurope.com\/wp-content\/uploads\/2025\/11\/fab-768x512.jpg 768w, https:\/\/millerweldseurope.com\/wp-content\/uploads\/2025\/11\/fab.jpg 1080w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7824a0d elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"7824a0d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Fabienne Gehweiler<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-925bf3f elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"925bf3f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Vertriebsinnendienst Mitarbeiterin<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-881ec3a team-carousel_bio elementor-widget elementor-widget-text-editor\" data-id=\"881ec3a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Bei Miller zu arbeiten bedeutet, Teil eines gro\u00dfartigen Teams zu sein, das sich gegenseitig unterst\u00fctzt und gemeinsam w\u00e4chst. Der starke Zusammenhalt unter den Kolleginnen und Kollegen schafft ein vertrauensvolles und motivierendes Arbeitsumfeld. Kein Tag ist wie der andere \u2013 die Aufgaben sind abwechslungsreich und spannend. Das internationale Umfeld bringt dabei immer wieder neue Einfl\u00fcsse und macht die t\u00e4gliche Arbeit besonders vielseitig.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"4\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 von 6\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1e48a64 e-ecs-flex e-flex e-con-boxed e-con e-child\" data-id=\"1e48a64\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ecs_container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fdd3103 elementor-widget elementor-widget-image\" data-id=\"fdd3103\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/millerweldseurope.com\/wp-content\/uploads\/2025\/11\/testi_j_pelgrims-1024x683.jpg\" class=\"attachment-large size-large wp-image-54703\" alt=\"\" srcset=\"https:\/\/millerweldseurope.com\/wp-content\/uploads\/2025\/11\/testi_j_pelgrims-1024x683.jpg 1024w, https:\/\/millerweldseurope.com\/wp-content\/uploads\/2025\/11\/testi_j_pelgrims-300x200.jpg 300w, https:\/\/millerweldseurope.com\/wp-content\/uploads\/2025\/11\/testi_j_pelgrims-768x512.jpg 768w, https:\/\/millerweldseurope.com\/wp-content\/uploads\/2025\/11\/testi_j_pelgrims.jpg 1080w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c93e899 elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"c93e899\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Jan Pelgrims<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-af87957 elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"af87957\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Business Development Manager, Heating Systems<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bbd8cda team-carousel_bio elementor-widget elementor-widget-text-editor\" data-id=\"bbd8cda\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Bei ITW Welding und Miller zu arbeiten ist fantastisch. Man ist Teil eines Expertenteams, das die Welt des Schwei\u00dfens international mitgestaltet \u2013 und es ist gro\u00dfartig, zu dieser Gruppe zu geh\u00f6ren. Ich habe die M\u00f6glichkeit, Menschen mit unterschiedlichstem Hintergrund und aus verschiedenen Kulturen kennenzulernen. Meine Kolleg: innen sind ein vielf\u00e4ltiges, internationales Team \u2013 das bereichert das Leben enorm. Ich f\u00fchle mich in diesem Team sehr wertgesch\u00e4tzt. Mein Beitrag wird geh\u00f6rt, und es ist toll zu sehen, wie sich Produkte und Menschen in meiner Zeit bei Miller weiterentwickelt haben<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"5\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 von 6\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bb8ac56 e-ecs-flex e-flex e-con-boxed e-con e-child\" data-id=\"bb8ac56\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ecs_container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-11c8f72 elementor-widget elementor-widget-image\" data-id=\"11c8f72\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/millerweldseurope.com\/wp-content\/uploads\/2025\/11\/testi_f_gruske-1024x683.jpg\" class=\"attachment-large size-large wp-image-54708\" alt=\"\" srcset=\"https:\/\/millerweldseurope.com\/wp-content\/uploads\/2025\/11\/testi_f_gruske-1024x683.jpg 1024w, https:\/\/millerweldseurope.com\/wp-content\/uploads\/2025\/11\/testi_f_gruske-300x200.jpg 300w, https:\/\/millerweldseurope.com\/wp-content\/uploads\/2025\/11\/testi_f_gruske-768x512.jpg 768w, https:\/\/millerweldseurope.com\/wp-content\/uploads\/2025\/11\/testi_f_gruske.jpg 1080w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2701793 elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"2701793\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Franz Gruske<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a623aa3 elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"a623aa3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Demo Welder DACH<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-247aefa team-carousel_bio elementor-widget elementor-widget-text-editor\" data-id=\"247aefa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ein Motto, das mir meine Kolleginnen und Kollegen bei Miller vermittelt haben, ist: \u201eEs gibt nur L\u00f6sungen, keine Probleme.\u201c Dieser Ansatz motiviert mich jeden Tag aufs Neue und spiegelt den Spirit unseres Unternehmens perfekt wider.<br \/>Ich arbeite sehr gerne bei Miller, da hier meine Begeisterung f\u00fcr die Schwei\u00dftechnik auf erstklassige und innovative Maschinentechnik trifft. Besonders sch\u00e4tze ich die Vielfalt in unserem Team. Alle bringen unterschiedliche St\u00e4rken und Perspektiven ein, was f\u00fcr ein harmonisches und inspirierendes Arbeitsumfeld sorgt.<br \/>Es macht mir immer wieder gro\u00dfen Spa\u00df, unsere Technik bei Kunden und auf Messen vorzustellen und direkt zu erleben, wie unsere L\u00f6sungen \u00fcberzeugen. Jeder Tag bringt neue Herausforderungen und spannende Aufgaben mit sich, die mich fachlich und pers\u00f6nlich wachsen lassen \u2013 das macht die Arbeit bei Miller so abwechslungsreich und bereichernd.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"6\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 von 6\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-310cebe e-ecs-flex e-flex e-con-boxed e-con e-child\" data-id=\"310cebe\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ecs_container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-80317f8 elementor-widget elementor-widget-image\" data-id=\"80317f8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/millerweldseurope.com\/wp-content\/uploads\/2025\/11\/testi_p_brix-1024x683.jpg\" class=\"attachment-large size-large wp-image-54713\" alt=\"\" srcset=\"https:\/\/millerweldseurope.com\/wp-content\/uploads\/2025\/11\/testi_p_brix-1024x683.jpg 1024w, https:\/\/millerweldseurope.com\/wp-content\/uploads\/2025\/11\/testi_p_brix-300x200.jpg 300w, https:\/\/millerweldseurope.com\/wp-content\/uploads\/2025\/11\/testi_p_brix-768x512.jpg 768w, https:\/\/millerweldseurope.com\/wp-content\/uploads\/2025\/11\/testi_p_brix.jpg 1080w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-58f61fb elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"58f61fb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Paul Brix<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-24f1e48 elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"24f1e48\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Supply Chain \/ Product Manager<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ac742ed team-carousel_bio elementor-widget elementor-widget-text-editor\" data-id=\"ac742ed\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ich bin im Jahr 2022 eingetreten und habe seitdem\u00a0viele positive Erfahrungen gemacht. Miller zeichnet sich durch flache Hierarchien und Teamwork aus, was im Berufsalltag deutlich zu sp\u00fcren ist.\u00a0Gleichzeitig bietet das internationale Umfeld reichlich Abwechslung im T\u00e4tigkeitsbereich.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Voriger\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t<\/div>\n\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"N\u00e4chster\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3d68797 career-counter e-ecs-flex e-flex e-con-boxed e-con e-parent\" data-id=\"3d68797\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;,&quot;ecs_container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-6975bf0 e-con-full e-ecs-flex e-flex e-con e-child\" data-id=\"6975bf0\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ecs_container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e71bcb3 elementor-widget elementor-widget-counter\" data-id=\"e71bcb3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<span class=\"elementor-counter-title\">Teamplayer<br> Weltweit<\/span>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\">&gt;<\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"1000\" data-to-value=\"300\" data-from-value=\"0\" data-delimiter=\".\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\"><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-07641a4 e-con-full e-ecs-flex e-flex e-con e-child\" data-id=\"07641a4\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ecs_container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-96216b4 elementor-widget elementor-widget-counter\" data-id=\"96216b4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<span class=\"elementor-counter-title\">Kulturelle<br>Vielfalt<\/span>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\">&gt;<\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"1000\" data-to-value=\"16\" data-from-value=\"0\" data-delimiter=\".\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\">&nbsp;L\u00e4nder<\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6ed0bca e-con-full e-ecs-flex e-flex e-con e-child\" data-id=\"6ed0bca\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ecs_container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8e3d5a4 elementor-widget elementor-widget-counter\" data-id=\"8e3d5a4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<span class=\"elementor-counter-title\">Frauen sorgen f\u00fcr Diversity  in unserem Tech-Umfeld<\/span>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\">&gt;<\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"1000\" data-to-value=\"20\" data-from-value=\"0\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\">%<\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f0208a6 e-con-full e-ecs-flex e-flex e-con e-child\" data-id=\"f0208a6\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ecs_container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7c76149 elementor-widget elementor-widget-counter\" data-id=\"7c76149\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<span class=\"elementor-counter-title\">L\u00e4nder, in die wir unsere Produkte liefern<\/span>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\">&gt;<\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"1000\" data-to-value=\"80\" data-from-value=\"0\" data-delimiter=\".\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\"><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-56102f2 e-ecs-flex e-flex e-con-boxed e-con e-parent\" data-id=\"56102f2\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;ecs_container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-dd2f62b elementor-widget elementor-widget-heading\" data-id=\"dd2f62b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Lass uns zusammen starten <br>und Gro\u00dfes erreichen<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7c4fa14 e-ecs-flex e-flex e-con-boxed e-con e-parent\" data-id=\"7c4fa14\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;ecs_container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-14a3ecf e-con-full e-ecs-flex e-flex e-con e-child\" data-id=\"14a3ecf\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;ecs_container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3c278d9 elementor-widget elementor-widget-image\" data-id=\"3c278d9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/millerweldseurope.com\/wp-content\/uploads\/2025\/11\/section_expert-1-1024x683.jpg\" class=\"attachment-large size-large wp-image-54790\" alt=\"\" srcset=\"https:\/\/millerweldseurope.com\/wp-content\/uploads\/2025\/11\/section_expert-1-1024x683.jpg 1024w, https:\/\/millerweldseurope.com\/wp-content\/uploads\/2025\/11\/section_expert-1-300x200.jpg 300w, https:\/\/millerweldseurope.com\/wp-content\/uploads\/2025\/11\/section_expert-1-768x512.jpg 768w, https:\/\/millerweldseurope.com\/wp-content\/uploads\/2025\/11\/section_expert-1.jpg 1080w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9d7e83c elementor-widget elementor-widget-heading\" data-id=\"9d7e83c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">Experten<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-971d625 elementor-widget elementor-widget-text-editor\" data-id=\"971d625\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Du liebst was Du tust, m\u00f6chtest etwas bewegen und mit uns wachsen? Ob als Fachgenie, Organisationstalent, Macher oder kreativer Kopf &#8211; bei uns macht jeder den Unterschied. Du bringst deine Ideen ein, tr\u00e4gst zur Teampower bei und sorgst Hand in Hand mit anderen f\u00fcr Millers Erfolg. Wir unterst\u00fctzen Dich \u2013 um t\u00e4glich einen tollen Job zu machen und Dich weiterzuentwickeln.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-610fd03 e-con-full e-ecs-flex e-flex e-con e-child\" data-id=\"610fd03\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;ecs_container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-dc67f37 elementor-widget elementor-widget-image\" data-id=\"dc67f37\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/millerweldseurope.com\/wp-content\/uploads\/2025\/11\/section_leading-1-1024x683.jpg\" class=\"attachment-large size-large wp-image-54795\" alt=\"\" srcset=\"https:\/\/millerweldseurope.com\/wp-content\/uploads\/2025\/11\/section_leading-1-1024x683.jpg 1024w, https:\/\/millerweldseurope.com\/wp-content\/uploads\/2025\/11\/section_leading-1-300x200.jpg 300w, https:\/\/millerweldseurope.com\/wp-content\/uploads\/2025\/11\/section_leading-1-768x512.jpg 768w, https:\/\/millerweldseurope.com\/wp-content\/uploads\/2025\/11\/section_leading-1.jpg 1080w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9a7cb3c elementor-widget elementor-widget-heading\" data-id=\"9a7cb3c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">F\u00fchrungskr\u00e4fte<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fca385e elementor-widget elementor-widget-text-editor\" data-id=\"fca385e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Du gehst als Motivierer, Optimierer, Wegbereiter und Impulsgeber voll auf? Ob als Teamleiter und Manager \u2013 Du gestaltest und realisierst die Strategie, sch\u00f6pfst Potenziale aus, treibst Ver\u00e4nderungen voran, verk\u00f6rperst unsere Werte und entwickelst dein Team als Unternehmer im Unternehmen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-879965b e-ecs-flex e-flex e-con-boxed e-con e-parent\" data-id=\"879965b\" data-element_type=\"container\" data-e-type=\"container\" id=\"current_openings\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;ecs_container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3b8a238 elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"3b8a238\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Dein k\u00fcnftiger Job<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9c91af2 elementor-widget elementor-widget-shortcode\" data-id=\"9c91af2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><script type=\"application\/ld+json\">\n{\n    \"@context\": \"https:\/\/schema.org\",\n    \"@graph\": [\n        {\n            \"@type\": \"JobPosting\",\n            \"title\": \"Schwei\u00dfer (m\/w\/d)\",\n            \"description\": \"Durch Test-Schwei\u00dfungen unserer gefertigten Endprodukte stellen wir die Erfu\u0308llung unserer hohen Qualit\u00e4tsstandards \u201emade inGermany\u201c in der Schwei\u00dffu\u0308lldrahtfertigung sicher. In unserem Schwei\u00dflabor tragen Sie die Verantwortung fu\u0308r Probeschwei\u00dfungenund leisten einen wichtigen Beitrag zur finalen Freigabe unserer Produkte.\\n\\nResponsibilities: Sie fu\u0308hren Schwei\u00dfungen in unserem Labor am Standort Altleiningen durch und beurteilen Produktneu- sowie -weiterentwicklungen (u. a. mechanische Gu\u0308tepru\u0308fungen, chemische Kennwertermittlungen, etc.); Sie erstelle Pru\u0308fberichte bzw. Zeugnisse und stellen eine saubere Dokumentation von Schwei\u00dfungen sicher; Sie fu\u0308hren eigenst\u00e4ndig Produkt- und Anwendungsschulungen fu\u0308r unsere H\u00e4ndler, Endkunden und Vertriebsteams durch; Bei Kundenreklamationen unterstu\u0308tzen sie uns mit technischer Expertise vor Ort bei Kunden (Reiset\u00e4tigkeit; Bei Interesse besteht die M\u00f6glichkeit Produktvorfu\u0308hrungen bei Kunden in Europa durchzufu\u0308hren; Sie bringen Ihre fundierte Erfahrung und Kenntnisse ein, um bei Bedarf Kolleginnen und Kollegen zu schulen; Bei Wunsch auf eine langfristige Weiterentwicklung besteht die Option Verantwortung fu\u0308r weitere Aufgaben zu u\u0308bernehmen\\n\\nRequirements: Abgeschlossene Berufsausbildung der Fachrichtung Metall; Metallurgische und technologische Kenntnisse (Grundwerkstoffe und Schwei\u00dfverfahren; Schwerpunkt: MAG- und Stabelektrodenschwei\u00dfen); Abgeschlossene Weiterbildung zum European- Welding-Specialist (EWS \/ SFM) wu\u0308nschenswert; Ausgepr\u00e4gte Teamorientierung, eigenst\u00e4ndige und pr\u00e4zise Arbeitsweise; Sicheres, u\u0308berzeugendes Auftreten sowie Freude an der Kommunikation mit Kunden; Hohe Leidenschaft fu\u0308r herausragende Schwei\u00dfergebnisse; Sehr gute Deutsch- und Englischkenntnisse\",\n            \"datePosted\": \"2026-08-21T13:32:01+02:00\",\n            \"identifier\": {\n                \"@type\": \"PropertyValue\",\n                \"name\": \"ITW Welding GmbH\",\n                \"value\": \"57287\"\n            },\n            \"hiringOrganization\": {\n                \"@type\": \"Organization\",\n                \"name\": \"ITW Welding GmbH\",\n                \"sameAs\": \"https:\/\/www.itwwelding.com\"\n            },\n            \"url\": \"https:\/\/millerweldseurope.com\/de\/careers\/schweiser-m-w-d\/\",\n            \"applicationContact\": {\n                \"@type\": \"ContactPoint\",\n                \"url\": \"https:\/\/millerweldseurope.com\/de\/careers\/schweiser-m-w-d\/\"\n            },\n            \"employmentType\": \"FULL_TIME\",\n            \"jobLocation\": {\n                \"@type\": \"Place\",\n                \"address\": {\n                    \"@type\": \"PostalAddress\",\n                    \"addressLocality\": \"Altleiningen\",\n                    \"addressCountry\": \"Deutschland\"\n                }\n            }\n        },\n        {\n            \"@type\": \"JobPosting\",\n            \"title\": \"Technischer Produkt Manager \u2013 Schwei\u00dfsysteme &amp; Anwendungen (m\/w\/d)\",\n            \"description\": \"Als Teil unseres Produktmanagementteams f\u00fcr unsere Miller Schwei\u00df- und Induction Heating Produkte leisten Sie einen wichtigen Beitrag in der Erschlie\u00dfung neuer Gesch\u00e4ftsfelder. Sie leiten aus Kundenbesuchen Anforderungen an unser zuk\u00fcnftiges Produktportfolio ab und sind interner Ansprechpartner f\u00fcr unser Vertriebs- und Kundenserviceteam.\\n\\nResponsibilities: Sie sind der erste Ansprechpartner f\u00fcr andere Abteilungen bei technischen und preisbezogenen Fragen rund um unsere Produkte; Sie managen das Produkt entlang des gesamten Produktlebenszyklus; Sie kommunizieren mit ausgew\u00e4hlten Lieferanten und wichtigen Kunden in Zusammenhang mit Produktentwicklungen und -anfragen; Sie leiten Produktneuentwicklungsprojekte; Sie f\u00fchren Kundenbesuche durch und leiten daraus Anforderungen f\u00fcr neue Produkte ab; Sie f\u00fchren Marktanalysen durch und entwickeln Go to Market Strategien; Sie \u00fcbernehmen die Anlage und Pflege von Artikeln und St\u00fccklisten in SAP; Sie sind f\u00fcr unsere Preislisten verantwortlich und stellen deren Aktualit\u00e4t sicher, bei Bedarf nehmen Sie Preisneukalkulationen vor; Sie erstellen technische Dokumentationen und Marketingmaterialien; Sie stellen sicher, dass erforderliche Produktinformationen jederzeit zur Verf\u00fcgung stehen\\n\\nRequirements: Erfolgreich abgeschlossenes technisches oder betriebswirtschaftliches (mit relevanter Erfahrung im technischen\/industriellen Umfeld) Studium; Vorkenntnisse in der Schwei\u00dftechnik idealerweise bereits vorhanden; 3-5 Jahre Berufserfahrung im Produktmanagement im technisch gepr\u00e4gten Umfeld (Schwei\u00dftechnik, F\u00fcgetechnik, Metallverarbeitung oder verwandter Industriebereich); Sie begeistern sich f\u00fcr Innovationen und technisch anspruchsvolle Herausforderungen spornen Sie an; Vorkenntnisse im Bereich Automatisierung sind hilfreich, aber nicht erforderlich; Sie arbeiten strukturiert, l\u00f6sungsorientiert, verantwortungsbewusst und proaktiv; Sie \u00fcbernehmen gerne die F\u00fchrung und k\u00f6nnen Projekte leiten; Sie arbeiten gerne eigenst\u00e4ndig und sind gleicherma\u00dfen ein echter Teamplayer; Sie haben Freude an der Interaktion mit anderen Abteilungen und an der Auseinandersetzung mit Kundenbed\u00fcrfnissen; Sie erkennen Kundenbed\u00fcrfnisse und k\u00f6nnen diese in Produktanforderungen ableiten; Sie bringen flie\u00dfende Deutsch- und sichere Englischkenntnisse mit; Microsoft Grundkenntnisse; SAP-Grundkenntnisse; Reisebereitschaft von 25-30%\",\n            \"datePosted\": \"2026-08-13T09:41:24+02:00\",\n            \"identifier\": {\n                \"@type\": \"PropertyValue\",\n                \"name\": \"Miller\",\n                \"value\": \"57135\"\n            },\n            \"hiringOrganization\": {\n                \"@type\": \"Organization\",\n                \"name\": \"Miller\",\n                \"sameAs\": \"https:\/\/www.itwwelding.com\"\n            },\n            \"url\": \"https:\/\/millerweldseurope.com\/de\/careers\/technischer-produkt-manager-schweisssysteme-anwendungen-m-w-d\/\",\n            \"applicationContact\": {\n                \"@type\": \"ContactPoint\",\n                \"url\": \"https:\/\/millerweldseurope.com\/de\/careers\/technischer-produkt-manager-schweisssysteme-anwendungen-m-w-d\/\"\n            },\n            \"employmentType\": \"FULL_TIME\",\n            \"jobLocation\": {\n                \"@type\": \"Place\",\n                \"address\": {\n                    \"@type\": \"PostalAddress\",\n                    \"addressLocality\": \"Singen\",\n                    \"addressCountry\": \"Deutschland\"\n                }\n            }\n        },\n        {\n            \"@type\": \"JobPosting\",\n            \"title\": \"Mitarbeiter Produktion (m\/w\/d)\",\n            \"description\": \"Unsere innovativen Schwei\u00dfdr\u00e4hte werden in Altleiningen mit jahrzehntelanger Tradition und Produktqualit\u00e4t \u201emade in Germany\u201c produziert. Mit unseren Produkten l\u00f6sen wir die schwierigsten Herausforderungen in der Schwei\u00dftechnik. Somit leisten Sie in der Produktion einen wichtigen Beitrag zu unserer hohen Produktqualit\u00e4t und zu unserem Gesch\u00e4ftserfolg.\\n\\nResponsibilities: Sie sind verantwortlich fu\u0308r die Einstellung, \u00dcberwachung und Bedienung von Produktionsmaschinen; Sie sorgen fu\u0308r die Einhaltung der Qualit\u00e4tsvorgaben nach Arbeitsanweisung; Sie fu\u0308hren technische Einstellarbeiten an den Anlagen durch und beheben St\u00f6rungen; Sie erstellen Produktionsprotokolle; Sie fu\u0308hren Reinigungst\u00e4tigkeiten an Maschinen und im Produktionsumfeld aus; Sie sorgen fu\u0308r eine ordentliche Lagerung von Produkten und Bestandteilen fu\u0308r die Produktion; Sie transportieren Produkte oder Einzelteile betriebsintern weiter\\n\\nRequirements: Abgeschlossene technische oder handwerkliche Berufsausbildung, bspw. als Maschinen- und Anlagenfu\u0308hrer (m\/w\/d), von Vorteil; Ausgepr\u00e4gtes technisches Verst\u00e4ndnis; Sie sind zuverl\u00e4ssig, sorgf\u00e4ltig, und arbeiten teamorientiert; Sie zeichnet eine selbstst\u00e4ndige, systematische, genaue Arbeitsweise aus; Sie haben ein offenes Auge zur Gew\u00e4hrleistung eines kontinuierlichen, unterbrechungsfreien Produktionsflusses; Sie beherrschen die deutsche Sprache flie\u00dfend; Bereitschaft fu\u0308r Schichtarbeit\",\n            \"datePosted\": \"2026-08-11T15:29:10+02:00\",\n            \"identifier\": {\n                \"@type\": \"PropertyValue\",\n                \"name\": \"ITW Welding GmbH\",\n                \"value\": \"57128\"\n            },\n            \"hiringOrganization\": {\n                \"@type\": \"Organization\",\n                \"name\": \"ITW Welding GmbH\",\n                \"sameAs\": \"https:\/\/www.itwwelding.com\"\n            },\n            \"url\": \"https:\/\/millerweldseurope.com\/de\/careers\/mitarbeiter-produktion-m-w-d\/\",\n            \"applicationContact\": {\n                \"@type\": \"ContactPoint\",\n                \"url\": \"https:\/\/millerweldseurope.com\/de\/careers\/mitarbeiter-produktion-m-w-d\/\"\n            },\n            \"employmentType\": \"FULL_TIME\",\n            \"jobLocation\": {\n                \"@type\": \"Place\",\n                \"address\": {\n                    \"@type\": \"PostalAddress\",\n                    \"addressLocality\": \"Altleiningen\",\n                    \"addressCountry\": \"Deutschland\"\n                }\n            }\n        },\n        {\n            \"@type\": \"JobPosting\",\n            \"title\": \"After Sales Manager Europe and Africa (m\/w\/d)\",\n            \"description\": \"Als After Sales Manager (m\/w\/d) verantworten Sie die Steuerung und Weiterentwicklung unseres After Sales f\u00fcr unsere Miller Schwei\u00dfprodukte in Europa und Afrika. Sie f\u00fchren unser internationales Service Team und entwickeln unser Service Netzwerk weiter. Mit Ihrer Expertise und Ihren Ideen tragen Sie ma\u00dfgeblich zur Kundenzufriedenheit und zur kontinuierlichen Verbesserung unseres Services bei und verbinden strategisches Denken mit Hands-on-Mentalit\u00e4t.\\n\\nResponsibilities: Sie f\u00fchren und entwickeln unser technisches After Sales Team in Europa und Afrika, sodass ein starkes Team besteht, das sich \u00fcber L\u00e4ndergrenzen hinweg als Einheit versteht; Sie analysieren und steuern unser Netzwerk externer Service- und Reparaturpartner anhand eines strukturierten Ansatzes zur Qualifizierung von Servicepartnern; Sie identifizieren Trainingsbedarfe im Service-Netzwerk und entwickeln unsere Partner durch Schulung strategisch weiter; Sie analysieren Potenziale f\u00fcr Optimierung und Effizienzsteigerung durch Digitalisierung der Serviceprozesse; Sie bauen eine Wissensdatenbank zur Dokumentation von Probleml\u00f6sungen auf; Sie sind Ansprechpartner f\u00fcr Key Accounts und den Vertrieb in technischen Fragestellungen und unterst\u00fctzen bei Installation und Wartung von Anlagen; Sie analysieren komplexe Fehlerbilder und stellen nachhaltige L\u00f6sungen sicher; Sie erstellen Schulungsmaterial und koordinieren \u00dcbersetzungen; Sie leiten Produktverbesserungspotenziale aus Reparatur- und Garantief\u00e4llen f\u00fcr das Product Management ab; Sie planen die Ersatzteilelagerhaltung; Sie tracken KPIs und leiten Ma\u00dfnahmen zur Verbesserung ab\\n\\nRequirements: Erfolgreich abgeschlossenes elektrotechnisches Studium, alternativ allgemeintechnisches Studium in Kombination mit fundierter Erfahrung mit elektronischen Ger\u00e4ten; Mehrj\u00e4hrige Erfahrung im technischen Serviceumfeld; Erfahrung in der F\u00fchrung von Teams und der Zusammenarbeit im internationalen, interkulturellen Kontext; Selbstst\u00e4ndige, systematische, strategische und l\u00f6sungsorientierte Arbeitsweise; Unternehmerische Haltung und Affinit\u00e4t daf\u00fcr, den Status Quo kontinuierlich zu hinterfragen, Verbesserungen voranzutreiben und Strategien zielgerichtet zu realisieren; Kommunikationsst\u00e4rke, sicheres Auftreten sowie Freude daran, Teams zu entwickeln; Sicherer Umgang mit MS Office und digitale Affinit\u00e4t; Reisebereitschaft (ca. 25%); Flie\u00dfende Deutsch- und Englischkenntnisse\",\n            \"datePosted\": \"2026-06-25T10:59:44+02:00\",\n            \"identifier\": {\n                \"@type\": \"PropertyValue\",\n                \"name\": \"Miller\",\n                \"value\": \"57113\"\n            },\n            \"hiringOrganization\": {\n                \"@type\": \"Organization\",\n                \"name\": \"Miller\",\n                \"sameAs\": \"https:\/\/www.itwwelding.com\"\n            },\n            \"url\": \"https:\/\/millerweldseurope.com\/de\/careers\/after-sales-manager-europe-and-africa-m-w-d\/\",\n            \"applicationContact\": {\n                \"@type\": \"ContactPoint\",\n                \"url\": \"https:\/\/millerweldseurope.com\/de\/careers\/after-sales-manager-europe-and-africa-m-w-d\/\"\n            },\n            \"employmentType\": \"FULL_TIME\",\n            \"jobLocation\": {\n                \"@type\": \"Place\",\n                \"address\": {\n                    \"@type\": \"PostalAddress\",\n                    \"addressLocality\": \"Singen\",\n                    \"addressCountry\": \"Deutschland\"\n                }\n            }\n        },\n        {\n            \"@type\": \"JobPosting\",\n            \"title\": \"Area Sales Manager Spain (m\/f\/d)\",\n            \"description\": \"To strengthen our European sales team, we are looking for an experienced Sales Manager (all genders) for welding equipment and consumables to build long term, trustful relationships with our distributor partners and customers in Spain and to further expand our business with new customers in this region.\\n\\nResponsibilities: Sale of our technically sophisticated product range of welding equipment and consumables of our Miller\u00ae and Elga\u00ae brands; Application-technical consultation of users and distribution partners and presentation of our products by demonstrations; Extension of the existing customer base and further development of customer relations; Proactive customer acquisition in the sales area; Close cooperation with ITW Welding sales team, the internal sales department and our research & development department; Market and competition monitoring\\n\\nRequirements: Technical or sales education and experience with a good technical and commercial background in the field of complex technical products; Minimum of 3 years of professional experience in a sales, sales management or similar role, preferably in the welding equipment industry; Proven track record of developing positive customer relationships; Challenger mindset and ability to educate the end-user to think differently about their business; Disciplined, motivated and team-oriented mindset to succeed in a self-directed environment with little supervision\",\n            \"datePosted\": \"2025-10-29T15:00:25+01:00\",\n            \"identifier\": {\n                \"@type\": \"PropertyValue\",\n                \"name\": \"ITW Welding Products Spain\",\n                \"value\": \"54317\"\n            },\n            \"hiringOrganization\": {\n                \"@type\": \"Organization\",\n                \"name\": \"ITW Welding Products Spain\",\n                \"sameAs\": \"https:\/\/www.itwwelding.com\"\n            },\n            \"url\": \"https:\/\/millerweldseurope.com\/de\/careers\/area-sales-manager-iberia-m-f-d\/\",\n            \"applicationContact\": {\n                \"@type\": \"ContactPoint\",\n                \"url\": \"https:\/\/millerweldseurope.com\/wp-content\/uploads\/2025\/10\/2025_09_Regional_Sales_Manager_Iberia.pdf\"\n            },\n            \"employmentType\": \"FULL_TIME\",\n            \"jobLocation\": {\n                \"@type\": \"Place\",\n                \"address\": {\n                    \"@type\": \"PostalAddress\",\n                    \"addressLocality\": \"Nationwide in Spain\"\n                }\n            }\n        },\n        {\n            \"@type\": \"JobPosting\",\n            \"title\": \"Health, Safety &amp; Environmental Manager (m\/w\/d)\",\n            \"description\": \"Werden Sie Teil eines Unternehmens, das f\u00fcr seine Werte und seinen Einsatz f\u00fcr Sicherheit und Nachhaltigkeit steht!\\n\\nResponsibilities: Entwicklung und Umsetzung von Sicherheits-, Gesundheits- und Umweltstrategien mit dem Schwerpunkt auf praktische Ma\u00dfnahmen vor Ort; F\u00f6rderung unserer Sicherheitsphilosophie: \u201eJeder Unfall ist vermeidbar\u201c; Aufbau einer proaktiven Sicherheitskultur mit kontinuierlicher Verbesserung und Unfallpr\u00e4vention; Zusammenarbeit mit den Teams auf allen Ebenen, denn die Verantwortung f\u00fcr Arbeitssicherheit und den Schutz der Umwelt geht alle an; Sie entwickeln, implementieren und analysieren die HS&E-Initiativen und -Programme am Standort Altleiningen und sind f\u00fcr deren Umsetzung verantwortlich. Sie arbeiten bei Bedarf mit dem HS&E-Team des Unternehmens zusammen, um die \u00dcbereinstimmung mit den Initiativen und Richtlinien von ITW sicherzustellen; F\u00f6rderung eines betrieblichen Umfelds, das durch stabile Sicherheitsund Umweltmanagementprozesse ein \u00fcberdurchschnittliches Sicherheitsbewusstsein und Umweltbewusstsein erzeugt; Untersuchung von Sicherheitsvorf\u00e4llen, Ursachenanalyse und die Entwicklung von Pl\u00e4nen f\u00fcr Verbesserungsm\u00f6glichkeiten; Durchf\u00fchrung von Schulungen zur Arbeitssicherheit im Werk; Durchf\u00fchrung von Standortaudits und Unterst\u00fctzung bei beh\u00f6rdlichen Inspektionen und Routineuntersuchungen; Routinem\u00e4\u00dfige T\u00e4tigkeiten im Bereich der Verwaltung von Industrie- und Sonderabf\u00e4llen\\n\\nRequirements: Technische Ausbildung oder technisches Studium in Kombination mit einer Weiterbildung sowie Erfahrung im Bereich HS&E; Hands-on-Mentalit\u00e4t und Freude an praxisnaher Arbeit im Produktionsumfeld; Erfahrung bei der Implementierung von Sicherheitskonzepten in produzierenden Betrieben; Sie f\u00fchlen sich in einem aktiven Umfeld wohl und lieben Herausforderungen; Sie sind gerne in das Tagesgesch\u00e4ft eingebunden und verstehen es, Beziehungen zu den Kolleginnen und Kollegen aufzubauen; Sie besitzen Leidenschaft f\u00fcr die Verbesserung von Prozessen und die Steigerung von Effizienz und Effektivit\u00e4t. Es macht Ihnen Spa\u00df, einfache L\u00f6sungen f\u00fcr komplexe Herausforderungen zu finden, und Sie tun dies mit Gelassenheit und Entschlossenheit; Starke Kommunikationsf\u00e4higkeiten und Durchsetzungsverm\u00f6gen\",\n            \"datePosted\": \"2024-12-18T12:50:07+01:00\",\n            \"identifier\": {\n                \"@type\": \"PropertyValue\",\n                \"name\": \" ITW Welding GmbH\",\n                \"value\": \"55160\"\n            },\n            \"hiringOrganization\": {\n                \"@type\": \"Organization\",\n                \"name\": \" ITW Welding GmbH\",\n                \"sameAs\": \"https:\/\/www.itwwelding.com\"\n            },\n            \"url\": \"https:\/\/millerweldseurope.com\/de\/careers\/health-safety-environmental-manager-m-f-d\/\",\n            \"applicationContact\": {\n                \"@type\": \"ContactPoint\",\n                \"url\": \"https:\/\/millerweldseurope.com\/wp-content\/uploads\/2024\/12\/A4_Health_Safety_Enviromental_Manager.pdf\"\n            },\n            \"employmentType\": \"FULL_TIME\",\n            \"jobLocation\": {\n                \"@type\": \"Place\",\n                \"address\": {\n                    \"@type\": \"PostalAddress\",\n                    \"addressLocality\": \"Altleiningen\",\n                    \"addressCountry\": \"Deutschland\"\n                }\n            }\n        }\n    ]\n}\n<\/script><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e009023 elementor-widget__width-auto carrer-filter elementor-widget elementor-widget-taxonomy-filter\" data-id=\"e009023\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;selected_element&quot;:&quot;5cfff6f&quot;,&quot;taxonomy&quot;:&quot;job-type&quot;,&quot;multiple_selection&quot;:&quot;no&quot;,&quot;horizontal_scroll&quot;:&quot;disable&quot;}\" data-widget_type=\"taxonomy-filter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<search class=\"e-filter\" role=\"search\" data-base-url=\"https:\/\/millerweldseurope.com\/de\/\" data-page-num=\"1\">\n\t\t\t\t\t\t\t<button class=\"e-filter-item\" data-filter=\"managment\" aria-pressed=\"false\">Managment<\/button>\n\t\t\t\n\t\t\t\t\t\t\t\t\t<button class=\"e-filter-item\" data-filter=\"__all\" aria-pressed=\"true\">\n\t\t\t\tAll\t\t\t<\/button>\n\t\t\t\t\t<\/search>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5cfff6f elementor-widget__width-inherit elementor-grid-1 elementor-grid-tablet-1 elementor-grid-mobile-1 elementor-widget elementor-widget-loop-grid\" data-id=\"5cfff6f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;template_id&quot;:55176,&quot;columns&quot;:1,&quot;row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;columns_tablet&quot;:1,&quot;_skin&quot;:&quot;post&quot;,&quot;columns_mobile&quot;:&quot;1&quot;,&quot;edit_handle_selector&quot;:&quot;[data-elementor-type=\\&quot;loop-item\\&quot;]&quot;,&quot;row_gap_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"loop-grid.post\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-loop-container elementor-grid\" role=\"list\">\n\t\t<style id=\"loop-55176\">.elementor-55176 .elementor-element.elementor-element-2af7a53{--display:flex;--flex-direction:row;--container-widget-width:calc( ( 1 - var( --container-widget-flex-grow ) ) * 100% );--container-widget-height:100%;--container-widget-flex-grow:1;--container-widget-align-self:stretch;--flex-wrap-mobile:wrap;--align-items:center;--gap:10px 10px;--row-gap:10px;--column-gap:10px;--margin-top:10px;--margin-bottom:10px;--margin-left:10px;--margin-right:10px;--padding-top:10px;--padding-bottom:10px;--padding-left:10px;--padding-right:10px;}.elementor-55176 .elementor-element.elementor-element-2af7a53:not(.elementor-motion-effects-element-type-background), .elementor-55176 .elementor-element.elementor-element-2af7a53 > .elementor-motion-effects-container > .elementor-motion-effects-layer{background-color:var( --e-global-color-1220c3f );}.elementor-55176 .elementor-element.elementor-element-1ff9f87{--display:flex;}.elementor-widget-heading .elementor-heading-title{font-family:var( --e-global-typography-primary-font-family ), Sans-serif;font-weight:var( --e-global-typography-primary-font-weight );color:var( --e-global-color-primary );}.elementor-55176 .elementor-element.elementor-element-4dabd41 .elementor-heading-title{font-family:var( --e-global-typography-f1f5ff0-font-family ), Sans-serif;font-size:var( --e-global-typography-f1f5ff0-font-size );font-weight:var( --e-global-typography-f1f5ff0-font-weight );line-height:var( --e-global-typography-f1f5ff0-line-height );letter-spacing:var( --e-global-typography-f1f5ff0-letter-spacing );word-spacing:var( --e-global-typography-f1f5ff0-word-spacing );color:var( --e-global-color-dccbe4f );}.elementor-55176 .elementor-element.elementor-element-2e3b290{--display:flex;}.elementor-55176 .elementor-element.elementor-element-a4382b2{text-align:start;}.elementor-55176 .elementor-element.elementor-element-a4382b2 .elementor-heading-title{font-family:var( --e-global-typography-1651385-font-family ), Sans-serif;font-size:var( --e-global-typography-1651385-font-size );font-weight:var( --e-global-typography-1651385-font-weight );line-height:var( --e-global-typography-1651385-line-height );letter-spacing:var( --e-global-typography-1651385-letter-spacing );word-spacing:var( --e-global-typography-1651385-word-spacing );color:var( --e-global-color-text );}.elementor-55176 .elementor-element.elementor-element-3bf7482{--display:flex;}.elementor-55176 .elementor-element.elementor-element-1d94dd9{text-align:start;}.elementor-55176 .elementor-element.elementor-element-1d94dd9 .elementor-heading-title{font-family:var( --e-global-typography-1651385-font-family ), Sans-serif;font-size:var( --e-global-typography-1651385-font-size );font-weight:var( --e-global-typography-1651385-font-weight );line-height:var( --e-global-typography-1651385-line-height );letter-spacing:var( --e-global-typography-1651385-letter-spacing );word-spacing:var( --e-global-typography-1651385-word-spacing );color:var( --e-global-color-text );}.elementor-55176 .elementor-element.elementor-element-b06f8fe{--display:flex;}.elementor-widget-icon-box.elementor-view-stacked .elementor-icon{background-color:var( --e-global-color-primary );}.elementor-widget-icon-box.elementor-view-framed .elementor-icon, .elementor-widget-icon-box.elementor-view-default .elementor-icon{fill:var( --e-global-color-primary );color:var( --e-global-color-primary );border-color:var( --e-global-color-primary );}.elementor-widget-icon-box .elementor-icon-box-title, .elementor-widget-icon-box .elementor-icon-box-title a{font-family:var( --e-global-typography-primary-font-family ), Sans-serif;font-weight:var( --e-global-typography-primary-font-weight );}.elementor-widget-icon-box .elementor-icon-box-title{color:var( --e-global-color-primary );}.elementor-widget-icon-box:has(:hover) .elementor-icon-box-title,\n\t\t\t\t\t .elementor-widget-icon-box:has(:focus) .elementor-icon-box-title{color:var( --e-global-color-primary );}.elementor-widget-icon-box .elementor-icon-box-description{font-family:var( --e-global-typography-text-font-family ), Sans-serif;color:var( --e-global-color-text );}.elementor-55176 .elementor-element.elementor-element-77fbab4 .elementor-icon-box-wrapper{align-items:center;text-align:end;gap:8px;}.elementor-55176 .elementor-element.elementor-element-77fbab4 .elementor-icon-box-title{margin-block-end:10px;color:var( --e-global-color-accent );}.elementor-55176 .elementor-element.elementor-element-77fbab4 .elementor-icon{font-size:16px;}.elementor-55176 .elementor-element.elementor-element-77fbab4 .elementor-icon-box-title, .elementor-55176 .elementor-element.elementor-element-77fbab4 .elementor-icon-box-title a{font-family:var( --e-global-typography-3c845cd-font-family ), Sans-serif;font-size:var( --e-global-typography-3c845cd-font-size );font-weight:var( --e-global-typography-3c845cd-font-weight );line-height:var( --e-global-typography-3c845cd-line-height );letter-spacing:var( --e-global-typography-3c845cd-letter-spacing );word-spacing:var( --e-global-typography-3c845cd-word-spacing );}@media(min-width:768px){.elementor-55176 .elementor-element.elementor-element-1ff9f87{--width:29.993%;}.elementor-55176 .elementor-element.elementor-element-2e3b290{--width:24.973%;}.elementor-55176 .elementor-element.elementor-element-3bf7482{--width:24.895%;}.elementor-55176 .elementor-element.elementor-element-b06f8fe{--width:20.041%;}}@media(max-width:1366px){.elementor-55176 .elementor-element.elementor-element-4dabd41 .elementor-heading-title{font-size:var( --e-global-typography-f1f5ff0-font-size );line-height:var( --e-global-typography-f1f5ff0-line-height );letter-spacing:var( --e-global-typography-f1f5ff0-letter-spacing );word-spacing:var( --e-global-typography-f1f5ff0-word-spacing );}.elementor-55176 .elementor-element.elementor-element-a4382b2 .elementor-heading-title{font-size:var( --e-global-typography-1651385-font-size );line-height:var( --e-global-typography-1651385-line-height );letter-spacing:var( --e-global-typography-1651385-letter-spacing );word-spacing:var( --e-global-typography-1651385-word-spacing );}.elementor-55176 .elementor-element.elementor-element-1d94dd9 .elementor-heading-title{font-size:var( --e-global-typography-1651385-font-size );line-height:var( --e-global-typography-1651385-line-height );letter-spacing:var( --e-global-typography-1651385-letter-spacing );word-spacing:var( --e-global-typography-1651385-word-spacing );}.elementor-55176 .elementor-element.elementor-element-77fbab4 .elementor-icon-box-title, .elementor-55176 .elementor-element.elementor-element-77fbab4 .elementor-icon-box-title a{font-size:var( --e-global-typography-3c845cd-font-size );line-height:var( --e-global-typography-3c845cd-line-height );letter-spacing:var( --e-global-typography-3c845cd-letter-spacing );word-spacing:var( --e-global-typography-3c845cd-word-spacing );}}@media(max-width:1024px){.elementor-55176 .elementor-element.elementor-element-4dabd41 .elementor-heading-title{font-size:var( --e-global-typography-f1f5ff0-font-size );line-height:var( --e-global-typography-f1f5ff0-line-height );letter-spacing:var( --e-global-typography-f1f5ff0-letter-spacing );word-spacing:var( --e-global-typography-f1f5ff0-word-spacing );}.elementor-55176 .elementor-element.elementor-element-a4382b2 .elementor-heading-title{font-size:var( --e-global-typography-1651385-font-size );line-height:var( --e-global-typography-1651385-line-height );letter-spacing:var( --e-global-typography-1651385-letter-spacing );word-spacing:var( --e-global-typography-1651385-word-spacing );}.elementor-55176 .elementor-element.elementor-element-1d94dd9 .elementor-heading-title{font-size:var( --e-global-typography-1651385-font-size );line-height:var( --e-global-typography-1651385-line-height );letter-spacing:var( --e-global-typography-1651385-letter-spacing );word-spacing:var( --e-global-typography-1651385-word-spacing );}.elementor-55176 .elementor-element.elementor-element-77fbab4 .elementor-icon-box-title, .elementor-55176 .elementor-element.elementor-element-77fbab4 .elementor-icon-box-title a{font-size:var( --e-global-typography-3c845cd-font-size );line-height:var( --e-global-typography-3c845cd-line-height );letter-spacing:var( --e-global-typography-3c845cd-letter-spacing );word-spacing:var( --e-global-typography-3c845cd-word-spacing );}}@media(max-width:767px){.elementor-55176 .elementor-element.elementor-element-2af7a53{--gap:0px 0px;--row-gap:0px;--column-gap:0px;}.elementor-55176 .elementor-element.elementor-element-4dabd41 .elementor-heading-title{font-size:var( --e-global-typography-f1f5ff0-font-size );line-height:var( --e-global-typography-f1f5ff0-line-height );letter-spacing:var( --e-global-typography-f1f5ff0-letter-spacing );word-spacing:var( --e-global-typography-f1f5ff0-word-spacing );}.elementor-55176 .elementor-element.elementor-element-a4382b2{text-align:start;}.elementor-55176 .elementor-element.elementor-element-a4382b2 .elementor-heading-title{font-size:var( --e-global-typography-1651385-font-size );line-height:var( --e-global-typography-1651385-line-height );letter-spacing:var( --e-global-typography-1651385-letter-spacing );word-spacing:var( --e-global-typography-1651385-word-spacing );}.elementor-55176 .elementor-element.elementor-element-1d94dd9{text-align:start;}.elementor-55176 .elementor-element.elementor-element-1d94dd9 .elementor-heading-title{font-size:var( --e-global-typography-1651385-font-size );line-height:var( --e-global-typography-1651385-line-height );letter-spacing:var( --e-global-typography-1651385-letter-spacing );word-spacing:var( --e-global-typography-1651385-word-spacing );}.elementor-55176 .elementor-element.elementor-element-77fbab4 .elementor-icon-box-wrapper{gap:15px;}.elementor-55176 .elementor-element.elementor-element-77fbab4 .elementor-icon-box-title{margin-block-end:10px;}.elementor-55176 .elementor-element.elementor-element-77fbab4 .elementor-icon-box-title, .elementor-55176 .elementor-element.elementor-element-77fbab4 .elementor-icon-box-title a{font-size:var( --e-global-typography-3c845cd-font-size );line-height:var( --e-global-typography-3c845cd-line-height );letter-spacing:var( --e-global-typography-3c845cd-letter-spacing );word-spacing:var( --e-global-typography-3c845cd-word-spacing );}}<\/style>\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"55176\" class=\"elementor elementor-55176 elementor-54553 elementor-54553 e-loop-item e-loop-item-57287 post-57287 careers type-careers status-publish hentry\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<div class=\"elementor-element elementor-element-2af7a53 active-link-box active-link-box--blank e-ecs-flex e-flex e-con-boxed e-con e-parent\" data-id=\"2af7a53\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;ecs_container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-1ff9f87 e-con-full e-ecs-flex e-flex e-con e-child\" data-id=\"1ff9f87\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ecs_container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4dabd41 elementor-widget elementor-widget-heading\" data-id=\"4dabd41\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Schwei\u00dfer (m\/w\/d)<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2e3b290 e-con-full e-ecs-flex e-flex e-con e-child\" data-id=\"2e3b290\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ecs_container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a4382b2 elementor-widget elementor-widget-heading\" data-id=\"a4382b2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">ITW Welding GmbH<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3bf7482 e-con-full e-ecs-flex e-flex e-con e-child\" data-id=\"3bf7482\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ecs_container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1d94dd9 elementor-widget elementor-widget-heading\" data-id=\"1d94dd9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Altleiningen, Deutschland<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b06f8fe e-con-full e-ecs-flex e-flex e-con e-child\" data-id=\"b06f8fe\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ecs_container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-77fbab4 elementor-position-inline-end elementor-mobile-position-inline-end elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"77fbab4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/millerweldseurope.com\/de\/careers\/schweiser-m-w-d\/\" class=\"elementor-icon\" tabindex=\"-1\" aria-label=\"Details anzeigen\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"17\" viewBox=\"0 0 16 17\" fill=\"none\"><path d=\"M13.9883 8.55078L9.44922 13.3633C9.36719 13.4727 9.23047 13.5 9.12109 13.5C9.01172 13.5 8.90234 13.4727 8.82031 13.3906C8.62891 13.2266 8.62891 12.9531 8.79297 12.7891L12.6211 8.6875H2.3125C2.06641 8.6875 1.875 8.49609 1.875 8.27734C1.875 8.05859 2.06641 7.8125 2.3125 7.8125H12.6211L8.79297 3.73828C8.62891 3.57422 8.62891 3.30078 8.82031 3.13672C9.01172 2.97266 9.28516 2.97266 9.44922 3.16406L13.9883 7.97656C14.1523 8.14062 14.1523 8.38672 13.9883 8.55078Z\" fill=\"#FF6900\"><\/path><\/svg>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"https:\/\/millerweldseurope.com\/de\/careers\/schweiser-m-w-d\/\" >\n\t\t\t\t\t\t\tDetails anzeigen\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"55176\" class=\"elementor elementor-55176 elementor-54553 elementor-54553 e-loop-item e-loop-item-57135 post-57135 careers type-careers status-publish has-post-thumbnail hentry\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<div class=\"elementor-element elementor-element-2af7a53 active-link-box active-link-box--blank e-ecs-flex e-flex e-con-boxed e-con e-parent\" data-id=\"2af7a53\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;ecs_container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-1ff9f87 e-con-full e-ecs-flex e-flex e-con e-child\" data-id=\"1ff9f87\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ecs_container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4dabd41 elementor-widget elementor-widget-heading\" data-id=\"4dabd41\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Technischer Produkt Manager \u2013 Schwei\u00dfsysteme &amp; Anwendungen (m\/w\/d)<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2e3b290 e-con-full e-ecs-flex e-flex e-con e-child\" data-id=\"2e3b290\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ecs_container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3bf7482 e-con-full e-ecs-flex e-flex e-con e-child\" data-id=\"3bf7482\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ecs_container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1d94dd9 elementor-widget elementor-widget-heading\" data-id=\"1d94dd9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Singen, Deutschland<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b06f8fe e-con-full e-ecs-flex e-flex e-con e-child\" data-id=\"b06f8fe\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ecs_container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-77fbab4 elementor-position-inline-end elementor-mobile-position-inline-end elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"77fbab4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/millerweldseurope.com\/de\/careers\/technischer-produkt-manager-schweisssysteme-anwendungen-m-w-d\/\" class=\"elementor-icon\" tabindex=\"-1\" aria-label=\"Details anzeigen\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"17\" viewBox=\"0 0 16 17\" fill=\"none\"><path d=\"M13.9883 8.55078L9.44922 13.3633C9.36719 13.4727 9.23047 13.5 9.12109 13.5C9.01172 13.5 8.90234 13.4727 8.82031 13.3906C8.62891 13.2266 8.62891 12.9531 8.79297 12.7891L12.6211 8.6875H2.3125C2.06641 8.6875 1.875 8.49609 1.875 8.27734C1.875 8.05859 2.06641 7.8125 2.3125 7.8125H12.6211L8.79297 3.73828C8.62891 3.57422 8.62891 3.30078 8.82031 3.13672C9.01172 2.97266 9.28516 2.97266 9.44922 3.16406L13.9883 7.97656C14.1523 8.14062 14.1523 8.38672 13.9883 8.55078Z\" fill=\"#FF6900\"><\/path><\/svg>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"https:\/\/millerweldseurope.com\/de\/careers\/technischer-produkt-manager-schweisssysteme-anwendungen-m-w-d\/\" >\n\t\t\t\t\t\t\tDetails anzeigen\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"55176\" class=\"elementor elementor-55176 elementor-54553 elementor-54553 e-loop-item e-loop-item-57128 post-57128 careers type-careers status-publish hentry\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<div class=\"elementor-element elementor-element-2af7a53 active-link-box active-link-box--blank e-ecs-flex e-flex e-con-boxed e-con e-parent\" data-id=\"2af7a53\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;ecs_container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-1ff9f87 e-con-full e-ecs-flex e-flex e-con e-child\" data-id=\"1ff9f87\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ecs_container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4dabd41 elementor-widget elementor-widget-heading\" data-id=\"4dabd41\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Mitarbeiter Produktion (m\/w\/d)<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2e3b290 e-con-full e-ecs-flex e-flex e-con e-child\" data-id=\"2e3b290\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ecs_container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a4382b2 elementor-widget elementor-widget-heading\" data-id=\"a4382b2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">ITW Welding GmbH<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3bf7482 e-con-full e-ecs-flex e-flex e-con e-child\" data-id=\"3bf7482\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ecs_container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1d94dd9 elementor-widget elementor-widget-heading\" data-id=\"1d94dd9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Altleiningen, Deutschland<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b06f8fe e-con-full e-ecs-flex e-flex e-con e-child\" data-id=\"b06f8fe\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ecs_container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-77fbab4 elementor-position-inline-end elementor-mobile-position-inline-end elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"77fbab4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/millerweldseurope.com\/de\/careers\/mitarbeiter-produktion-m-w-d\/\" class=\"elementor-icon\" tabindex=\"-1\" aria-label=\"Details anzeigen\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"17\" viewBox=\"0 0 16 17\" fill=\"none\"><path d=\"M13.9883 8.55078L9.44922 13.3633C9.36719 13.4727 9.23047 13.5 9.12109 13.5C9.01172 13.5 8.90234 13.4727 8.82031 13.3906C8.62891 13.2266 8.62891 12.9531 8.79297 12.7891L12.6211 8.6875H2.3125C2.06641 8.6875 1.875 8.49609 1.875 8.27734C1.875 8.05859 2.06641 7.8125 2.3125 7.8125H12.6211L8.79297 3.73828C8.62891 3.57422 8.62891 3.30078 8.82031 3.13672C9.01172 2.97266 9.28516 2.97266 9.44922 3.16406L13.9883 7.97656C14.1523 8.14062 14.1523 8.38672 13.9883 8.55078Z\" fill=\"#FF6900\"><\/path><\/svg>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"https:\/\/millerweldseurope.com\/de\/careers\/mitarbeiter-produktion-m-w-d\/\" >\n\t\t\t\t\t\t\tDetails anzeigen\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"55176\" class=\"elementor elementor-55176 elementor-54553 elementor-54553 e-loop-item e-loop-item-57113 post-57113 careers type-careers status-publish has-post-thumbnail hentry\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<div class=\"elementor-element elementor-element-2af7a53 active-link-box active-link-box--blank e-ecs-flex e-flex e-con-boxed e-con e-parent\" data-id=\"2af7a53\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;ecs_container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-1ff9f87 e-con-full e-ecs-flex e-flex e-con e-child\" data-id=\"1ff9f87\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ecs_container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4dabd41 elementor-widget elementor-widget-heading\" data-id=\"4dabd41\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">After Sales Manager Europe and Africa (m\/w\/d)<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2e3b290 e-con-full e-ecs-flex e-flex e-con e-child\" data-id=\"2e3b290\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ecs_container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3bf7482 e-con-full e-ecs-flex e-flex e-con e-child\" data-id=\"3bf7482\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ecs_container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1d94dd9 elementor-widget elementor-widget-heading\" data-id=\"1d94dd9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Singen, Deutschland<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b06f8fe e-con-full e-ecs-flex e-flex e-con e-child\" data-id=\"b06f8fe\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ecs_container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-77fbab4 elementor-position-inline-end elementor-mobile-position-inline-end elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"77fbab4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/millerweldseurope.com\/de\/careers\/after-sales-manager-europe-and-africa-m-w-d\/\" class=\"elementor-icon\" tabindex=\"-1\" aria-label=\"Details anzeigen\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"17\" viewBox=\"0 0 16 17\" fill=\"none\"><path d=\"M13.9883 8.55078L9.44922 13.3633C9.36719 13.4727 9.23047 13.5 9.12109 13.5C9.01172 13.5 8.90234 13.4727 8.82031 13.3906C8.62891 13.2266 8.62891 12.9531 8.79297 12.7891L12.6211 8.6875H2.3125C2.06641 8.6875 1.875 8.49609 1.875 8.27734C1.875 8.05859 2.06641 7.8125 2.3125 7.8125H12.6211L8.79297 3.73828C8.62891 3.57422 8.62891 3.30078 8.82031 3.13672C9.01172 2.97266 9.28516 2.97266 9.44922 3.16406L13.9883 7.97656C14.1523 8.14062 14.1523 8.38672 13.9883 8.55078Z\" fill=\"#FF6900\"><\/path><\/svg>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"https:\/\/millerweldseurope.com\/de\/careers\/after-sales-manager-europe-and-africa-m-w-d\/\" >\n\t\t\t\t\t\t\tDetails anzeigen\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"55176\" class=\"elementor elementor-55176 elementor-54553 elementor-54553 e-loop-item e-loop-item-54317 post-54317 careers type-careers status-publish has-post-thumbnail hentry job-type-managment\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<div class=\"elementor-element elementor-element-2af7a53 active-link-box active-link-box--blank e-ecs-flex e-flex e-con-boxed e-con e-parent\" data-id=\"2af7a53\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;ecs_container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-1ff9f87 e-con-full e-ecs-flex e-flex e-con e-child\" data-id=\"1ff9f87\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ecs_container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4dabd41 elementor-widget elementor-widget-heading\" data-id=\"4dabd41\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Area Sales Manager Spain (m\/f\/d)<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2e3b290 e-con-full e-ecs-flex e-flex e-con e-child\" data-id=\"2e3b290\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ecs_container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a4382b2 elementor-widget elementor-widget-heading\" data-id=\"a4382b2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">ITW Welding Products Spain<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3bf7482 e-con-full e-ecs-flex e-flex e-con e-child\" data-id=\"3bf7482\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ecs_container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1d94dd9 elementor-widget elementor-widget-heading\" data-id=\"1d94dd9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Nationwide in Spain<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b06f8fe e-con-full e-ecs-flex e-flex e-con e-child\" data-id=\"b06f8fe\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ecs_container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-77fbab4 elementor-position-inline-end elementor-mobile-position-inline-end elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"77fbab4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/millerweldseurope.com\/de\/careers\/area-sales-manager-iberia-m-f-d\/\" class=\"elementor-icon\" tabindex=\"-1\" aria-label=\"Details anzeigen\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"17\" viewBox=\"0 0 16 17\" fill=\"none\"><path d=\"M13.9883 8.55078L9.44922 13.3633C9.36719 13.4727 9.23047 13.5 9.12109 13.5C9.01172 13.5 8.90234 13.4727 8.82031 13.3906C8.62891 13.2266 8.62891 12.9531 8.79297 12.7891L12.6211 8.6875H2.3125C2.06641 8.6875 1.875 8.49609 1.875 8.27734C1.875 8.05859 2.06641 7.8125 2.3125 7.8125H12.6211L8.79297 3.73828C8.62891 3.57422 8.62891 3.30078 8.82031 3.13672C9.01172 2.97266 9.28516 2.97266 9.44922 3.16406L13.9883 7.97656C14.1523 8.14062 14.1523 8.38672 13.9883 8.55078Z\" fill=\"#FF6900\"><\/path><\/svg>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"https:\/\/millerweldseurope.com\/de\/careers\/area-sales-manager-iberia-m-f-d\/\" >\n\t\t\t\t\t\t\tDetails anzeigen\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"55176\" class=\"elementor elementor-55176 elementor-54553 elementor-54553 e-loop-item e-loop-item-55160 post-55160 careers type-careers status-publish has-post-thumbnail hentry\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<div class=\"elementor-element elementor-element-2af7a53 active-link-box active-link-box--blank e-ecs-flex e-flex e-con-boxed e-con e-parent\" data-id=\"2af7a53\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;ecs_container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-1ff9f87 e-con-full e-ecs-flex e-flex e-con e-child\" data-id=\"1ff9f87\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ecs_container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4dabd41 elementor-widget elementor-widget-heading\" data-id=\"4dabd41\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Health, Safety &amp; Environmental Manager (m\/w\/d)<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2e3b290 e-con-full e-ecs-flex e-flex e-con e-child\" data-id=\"2e3b290\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ecs_container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a4382b2 elementor-widget elementor-widget-heading\" data-id=\"a4382b2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"> ITW Welding GmbH<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3bf7482 e-con-full e-ecs-flex e-flex e-con e-child\" data-id=\"3bf7482\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ecs_container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1d94dd9 elementor-widget elementor-widget-heading\" data-id=\"1d94dd9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Altleiningen, Deutschland<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b06f8fe e-con-full e-ecs-flex e-flex e-con e-child\" data-id=\"b06f8fe\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ecs_container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-77fbab4 elementor-position-inline-end elementor-mobile-position-inline-end elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"77fbab4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/millerweldseurope.com\/de\/careers\/health-safety-environmental-manager-m-f-d\/\" class=\"elementor-icon\" tabindex=\"-1\" aria-label=\"Details anzeigen\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" height=\"17\" viewBox=\"0 0 16 17\" fill=\"none\"><path d=\"M13.9883 8.55078L9.44922 13.3633C9.36719 13.4727 9.23047 13.5 9.12109 13.5C9.01172 13.5 8.90234 13.4727 8.82031 13.3906C8.62891 13.2266 8.62891 12.9531 8.79297 12.7891L12.6211 8.6875H2.3125C2.06641 8.6875 1.875 8.49609 1.875 8.27734C1.875 8.05859 2.06641 7.8125 2.3125 7.8125H12.6211L8.79297 3.73828C8.62891 3.57422 8.62891 3.30078 8.82031 3.13672C9.01172 2.97266 9.28516 2.97266 9.44922 3.16406L13.9883 7.97656C14.1523 8.14062 14.1523 8.38672 13.9883 8.55078Z\" fill=\"#FF6900\"><\/path><\/svg>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"https:\/\/millerweldseurope.com\/de\/careers\/health-safety-environmental-manager-m-f-d\/\" >\n\t\t\t\t\t\t\tDetails anzeigen\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bdb7467 e-ecs-flex e-flex e-con-boxed e-con e-parent\" data-id=\"bdb7467\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;ecs_container_type&quot;:&quot;flex&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c799f89 elementor-widget elementor-widget-heading\" data-id=\"c799f89\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div clas